{"id":3753,"date":"2020-11-18T17:13:48","date_gmt":"2020-11-18T16:13:48","guid":{"rendered":"https:\/\/chronoinstitut.org\/?page_id=3753"},"modified":"2026-05-08T11:10:07","modified_gmt":"2026-05-08T09:10:07","slug":"zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob","status":"publish","type":"page","link":"https:\/\/salutologie.org\/en\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/","title":{"rendered":"Zertifikatslehrgang &#8211; LSB Salutologie 2 + Salutologie 1 und PSOB"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"block-area stripe wpb_row default with-border vc_row-fluid\"><div class=\"container clearfix\">\n\t<div class=\"vc_col-sm-12 wpb_column column_container\" style=\"\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1>Zertifikatslehrgang &#8211; LSB Salutologie 2 + Salutologie 1 und PSOB<\/h1>\n\n\t\t<\/div> \n\t<\/div> <div class=\"gap\" style=\"line-height: 20px; height: 20px;\"><\/div>\n\t<div class=\"wpb_single_image_wrapper center\"><div class=\"wpb_single_image wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t\t<div class=\"single_image_wrapper box-item\"><img class=\"\" src=\"https:\/\/salutologie.org\/wp-content\/uploads\/2025\/08\/pexels-fauxels-31842981-copy-1800x1000.jpg\" width=\"900\" height=\"500\" alt=\"pexels-fauxels-3184298(1) copy\" \/><\/div>\n\t\t<\/div> \n\t<\/div><\/div> \n\t\t<\/div> \n\t<\/div> \n<\/div><\/div><div class=\"block-area stripe wpb_row default with-border vc_row-fluid\"><div class=\"container clearfix\">\n\t<div class=\"vc_col-sm-6 wpb_column column_container\" style=\"\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table width=\"574\">\n<tbody>\n<tr>\n<td width=\"209\">Institution<\/td>\n<td width=\"365\"><strong>Akademie f\u00fcr Salutologie<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"209\">Abteilung<\/td>\n<td width=\"365\"><strong>Weiterbildungsakademie<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"209\">Dauer | ECTS<\/td>\n<td width=\"365\"><strong>Zertifikatslehrgang LSB Salutologie 2 + Salutologie 1 und PSOB<\/strong><\/p>\n<p><strong>6 Monate | 750 Stunden | 30 ECTS<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"209\">Abschluss<\/td>\n<td width=\"365\"><strong>Salutologin | Salutologe<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"209\">Qualifikationsniveau<\/td>\n<td width=\"365\"><strong>EQ\u00a0 EQR\/NQR: Stufe 6<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"209\">Lehrgangsleiter<\/td>\n<td width=\"365\"><strong>Dr. Peter Hauschild<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"209\">Lehrgangsart<\/td>\n<td width=\"365\"><strong>Blended-learning<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\t\t<\/div> \n\t<\/div> \n\t\t<\/div> \n\t<\/div> \n\n\t<div class=\"vc_col-sm-6 wpb_column column_container\" style=\"\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<table width=\"574\">\n<tbody>\n<tr>\n<td width=\"209\">Lehrgangsgeb\u00fchr<\/p>\n<p>Supervision<\/td>\n<td width=\"365\"><strong>\u20ac 5.950,- <\/strong>(Ratenzahlung auf Anfrage)<br \/>\nInkl. HRV-Sensor und Konto der Gesundheit<br \/>\n<strong>\u20ac\u00a0 \u00a0 400,-<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"209\">Unterrichtssprache<\/td>\n<td width=\"365\"><strong>Deutsch<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"209\">Ort der Durchf\u00fchrung<\/td>\n<td width=\"365\"><strong>Wien<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"209\">Beginn Aufnahmeverfahren<\/td>\n<td width=\"365\"><strong>August 2025<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"209\">Anmeldung<\/td>\n<td width=\"365\"><strong>Laufende Anmeldung m\u00f6glich<br \/>\n<\/strong><\/td>\n<\/tr>\n<tr>\n<td width=\"209\">Online-Informationsabend<\/td>\n<td width=\"365\"><strong>Jeweils nach Ank\u00fcndigung<br \/>\n<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n\n\t\t<\/div> \n\t<\/div> \n\t\t<\/div> \n\t<\/div> \n<\/div><\/div><div class=\"block-area stripe wpb_row default with-border vc_row-fluid\"><div class=\"container clearfix\">\n\t<div class=\"vc_col-sm-12 wpb_column column_container\" style=\"\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"vc_tta-container\" data-vc-action=\"collapse\"><div class=\"vc_general vc_tta vc_tta-accordion vc_tta-color-white vc_tta-style-classic vc_tta-shape-rounded vc_tta-o-shape-group vc_tta-controls-align-left vc_tta-o-no-fill\"><div class=\"vc_tta-panels-container\"><div class=\"vc_tta-panels\"><div class=\"vc_tta-panel vc_active\" id=\"1755701158671-f5fd519d-92e5\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1755701158671-f5fd519d-92e5\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Inhalt<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>Zertifikatslehrgang Salutologie 2 \u2013 Vertiefung &amp; Anwendung<\/strong><\/p>\n<p><strong>Titel: \u201eGesundheit leben \u2013 Ordnungsprozesse erkennen, begleiten und st\u00e4rken\u201c<\/strong><\/p>\n<p>Der Zertifikatslehrgang <em>Salutologie 2<\/em> richtet sich an Absolvent:innen des Basislehrgangs, die ihre salutologischen Kompetenzen vertiefen und praxisorientiert anwenden m\u00f6chten. Im Fokus stehen die Integration, Anwendung und Professionalisierung salutogener Ordnungsprozesse auf individueller, systemischer und gesellschaftlicher Ebene.<\/p>\n<p>Modul 1 f\u00fchrt in das erweiterte salutodynamische Denken ein: Das Ordnungsmodell sowie die Salutologie bieten ein theoretisches Fundament zur Erfassung innerer Ordnungsprozesse. Modul 2 widmet sich der salutometrischen Praxis \u2013 der Sichtbarmachung, Messung und Evaluation gesundheitlicher Entwicklungen.<\/p>\n<p>Im dritten Modul wird das Salutising-Modell anhand realer F\u00e4lle trainiert. Die Studierenden lernen, salutologische Beratung professionell und reflektiert umzusetzen. Modul 4 er\u00f6ffnet Wege zur Gestaltung gesundheitsf\u00f6rderlicher Lebensfelder \u2013 von Ern\u00e4hrung \u00fcber Schlaf bis zu Raumgestaltung und sozialer Resonanz.<\/p>\n<p>Modul 5 vermittelt Strategien zur Implementierung des digitalen Tools <em>Konto der Gesundheit<\/em> im Beratungsalltag. Ziel ist der Aufbau eines wirksamen salutologischen Interventionsportfolios. Im abschlie\u00dfenden Modul 6 entwickeln die Teilnehmenden ihre salutologische Identit\u00e4t, positionieren sich im Gesundheitsmarkt und reflektieren ihr Berufsethos.<\/p>\n<p>Mit 30 ECTS-Punkten und starkem Praxisbezug qualifiziert dieser Lehrgang Salutolog:innen zur Anwendung salutogener Konzepte in Beratung, Gesundheitsf\u00f6rderung und Pr\u00e4vention \u2013 mit wissenschaftlicher Tiefe und gesellschaftlicher Relevanz.<\/p>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><div class=\"vc_tta-panel\" id=\"1755701158679-5d4cd368-afa3\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1755701158679-5d4cd368-afa3\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Inhaltliche Schwerpunkte<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Im Zertifikatslehrgang <em>Salutologie 2<\/em> vertiefen die Teilnehmenden ihr Verst\u00e4ndnis f\u00fcr salutodynamische Prozesse und systemische Ordnungsmodelle als Grundlage menschlicher Selbstregulation. Anhand konkreter Fallbeispiele trainieren sie die Anwendung des Salutising-Modells und entwickeln wirksame Beratungsstrategien. Das <em>Konto der Gesundheit<\/em> wird praxisnah eingesetzt, um salutogene Interventionen gezielt zu planen, umzusetzen und zu evaluieren. Erweiterte Mess- und Analyseverfahren erlauben die pr\u00e4zise Beurteilung individueller Gesundheitsmuster.<\/p>\n<p>Zudem erarbeiten die Teilnehmenden Konzepte f\u00fcr einen salutogenen Lebensstil \u2013 unter Ber\u00fccksichtigung von Umweltfaktoren, Schlaf, Ern\u00e4hrung und Bewegung. Sie reflektieren ethische und rechtliche Aspekte salutologischer Beratung und st\u00e4rken ihre professionelle Identit\u00e4t als Salutolog:in. Dabei lernen sie, sich kompetent im Gesundheitsmarkt zu positionieren und interdisziplin\u00e4re Kooperationen aufzubauen. Grundkenntnisse in salutologischer Forschung und Wirkungsnachweis runden den praxis- und zukunftsorientierten Lehrgang ab.<\/p>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><div class=\"vc_tta-panel\" id=\"1755701314065-22295c98-8976\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1755701314065-22295c98-8976\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Learning Outcomes<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<ul>\n<li>salutodynamische Prozesse und das Ordnungsmodell der Salutologie erkl\u00e4ren und anwenden (Understanding);<\/li>\n<li>salutogene Lebensfelder (z.\u202fB. Schlaf, Ern\u00e4hrung, Umwelt) benennen und beschreiben (Remembering &amp; Understanding).<\/li>\n<li>salutogene Ma\u00dfnahmen und Interventionen auf konkrete Klientenf\u00e4lle \u00fcbertragen und evaluieren (Applying);<\/li>\n<li>das Konto der Gesundheit zur Verlaufsdokumentation und Zielplanung systematisch einsetzen (Applying);<\/li>\n<li>salutogene Messwerte interpretieren und in eine verst\u00e4ndliche Beratungssprache \u00fcbersetzen (Analyzing);<\/li>\n<li>die Wirksamkeit salutologischer Beratung im Hinblick auf Pr\u00e4vention und Lebensqualit\u00e4t kritisch reflektieren (Evaluating);<\/li>\n<li>ein zielgruppenorientiertes Beratungsportfolio f\u00fcr LSB-Klient:innen entwickeln (Creating);<\/li>\n<li>ein Kooperationskonzept zur Implementierung salutologischer Dienstleistungen in Institutionen entwerfen (Creating)<\/li>\n<\/ul>\n<p><em>Detaillierte Informationen zum Lehrplan Salutologie und der Psychosozialen Organisationsberatung erhalten Sie unter <\/em><a href=\"mailto:akademie@salutologie.org\"><em>akademie@salutologie.org<\/em><\/a><em>.<\/em><\/p>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><div class=\"vc_tta-panel\" id=\"1755701494829-03bd9e59-d52b\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1755701494829-03bd9e59-d52b\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Methoden<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Online-Zoomtermine<\/p>\n<p>Pr\u00e4senzlehrveranstaltungen<\/p>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><div class=\"vc_tta-panel\" id=\"1755701518829-3dd72c8e-6a98\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1755701518829-3dd72c8e-6a98\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Abschluss<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Teilnahmebest\u00e4tigung nach jeder Lehreinheit.<\/p>\n<p>Zertifikat nach Abschluss des gesamten Kurses.<\/p>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><div class=\"vc_tta-panel\" id=\"1755701539945-7e39a9f5-615e\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1755701539945-7e39a9f5-615e\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Zielgruppe<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Dieses Seminar richtet sich an Lebens- und Sozialberater:innen, Psycholog:innen, Psychotherapeut:innen, Mediziner:innen, P\u00e4dagog:innen, Sozialarbeiter:innen, Pflegepersonal und Studierende einschl\u00e4giger Fachrichtungen.<\/p>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><div class=\"vc_tta-panel\" id=\"1755701575188-137d78b5-f18f\" data-vc-content=\".vc_tta-panel-body\"><div class=\"vc_tta-panel-heading\"><h4 class=\"vc_tta-panel-title vc_tta-controls-icon-position-left\"><a href=\"#1755701575188-137d78b5-f18f\" data-vc-accordion data-vc-container=\".vc_tta-container\"><span class=\"vc_tta-title-text\">Lehrgangsleiter<\/span><i class=\"vc_tta-controls-icon vc_tta-controls-icon-plus\"><\/i><\/a><\/h4><\/div><div class=\"vc_tta-panel-body\">\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><strong>MMag. Dr. Peter Hauschild<\/strong><\/p>\n<ul>\n<li>Dr. der Psychotherapiewissenschaften<\/li>\n<li>Betriebswirt, Psychologe<\/li>\n<li>Salutologe<\/li>\n<\/ul>\n<p><strong>Arbeitsschwerpunkte:<\/strong><\/p>\n<ul>\n<li>Salutologie, Psychologie, Regulationsanalytiker, Entwickler des Kontos der Gesundheit und des HRV-Messger\u00e4tes Heartbalance<\/li>\n<li>Aufbau und Leitung des Institutes f\u00fcr Salutologie, Wien<\/li>\n<li>Entwickler und Begr\u00fcnder der Salutologie<\/li>\n<li>Initiator der Privatuniversit\u00e4t f\u00fcr Salutologie<\/li>\n<\/ul>\n\n\t\t<\/div> \n\t<\/div> <\/div><\/div><\/div><\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \n<\/div><\/div><div class=\"block-area stripe wpb_row default with-border vc_row-fluid\"><div class=\"container clearfix\">\n\t<div class=\"vc_col-sm-12 wpb_column column_container\" style=\"\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1>Anmeldung f\u00fcr weitere Information<\/h1>\n<p>Hier k\u00f6nnen Sie sich unverbindlich f\u00fcr den Online-Informationsabend, wie auch f\u00fcr weitere Information anmelden. Wir kontaktieren Sie pers\u00f6nlich per E-Mail und senden Ihnen alle weiteren Informationen zu.<\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f5456-o1\" lang=\"de-DE\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/3753#wpcf7-f5456-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Kontaktformular\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/3753#wpcf7-f5456-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"5456\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.8\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"de_DE\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f5456-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<p><label> Anrede<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"anrede\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"anrede\" \/><\/span> <\/label>\n<\/p>\n<p><label> Titel<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"titel\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"titel\" \/><\/span> <\/label>\n<\/p>\n<p><label> Vorname*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"first-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> Nachname*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"last-name\" \/><\/span> <\/label>\n<\/p>\n<p><label> E-Mail-Adresse*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n<\/p>\n<p><label> Telefonnummer<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"telefon\" \/><\/span> <\/label>\n<\/p>\n<p><label> Beruf<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"beruf\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"beruf\" \/><\/span> <\/label>\n<\/p>\n<p><label> Anmerkung<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span> <\/label>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"quiz-798\"><label><span class=\"wpcf7-quiz-label\">Bitte gib zur Best\u00e4tigung das Wort Salutologie ein?<\/span> <input size=\"40\" class=\"wpcf7-form-control wpcf7-quiz\" autocomplete=\"off\" aria-required=\"true\" aria-invalid=\"false\" type=\"text\" name=\"quiz-798\" \/><\/label><input type=\"hidden\" name=\"_wpcf7_quiz_answer_quiz-798\" value=\"b9b2fc3b03393d7eb36bb9d4444fc9fb\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-335\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-335\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Ich habe die <a href=\"\/en\/datenschutzrichtlinie\/\"> Datenschutzbestimmung<\/a> gelesen und gebe mein Einverst\u00e4ndnis, dass ich per E-Mail von der Universit\u00e4t f\u00fcr Salutologie kontaktiert werde.<\/span><\/label><\/span><\/span><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Senden\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n\n\n\t\t<\/div> \n\t<\/div> \n\t\t<\/div> \n\t<\/div> \n<\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"Zertifikatslehrgang - LSB Salutologie 2 + Salutologie 1 und PSOB Institution Akademie f\u00fcr Salutologie Abteilung Weiterbildungsakademie Dauer | ECTS Zertifikatslehrgang...","protected":false},"author":1,"featured_media":0,"parent":357,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zertifikatslehrgang - LSB Salutologie 2 + Salutologie 1 und PSOB - Akademie f\u00fcr Salutologie\u00ae<\/title>\n<meta name=\"description\" content=\"Der Lehrgang vertieft salutologisches Denken und bef\u00e4higt Sie, mit erweitertem Methodenrepertoire gesundheitsf\u00f6rdernd zu beraten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salutologie.org\/en\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Akademie f\u00fcr Salutologie \u2013 Zertifikatslehrgang \u2013 LSB Salutologie 2 + Salutologie 1 + PSOB | Zertifikat f\u00fcr Beratung &amp; Gesundheit\" \/>\n<meta property=\"og:description\" content=\"Der Lehrgang vertieft salutologisches Denken und bef\u00e4higt Sie, mit erweitertem Methodenrepertoire gesundheitsf\u00f6rdernd zu beraten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salutologie.org\/en\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/\" \/>\n<meta property=\"og:site_name\" content=\"Akademie f\u00fcr Salutologie\u00ae\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T09:10:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salutologie.org\/wp-content\/uploads\/2023\/01\/1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/salutologie.org\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/\",\"url\":\"https:\/\/salutologie.org\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/\",\"name\":\"Zertifikatslehrgang - LSB Salutologie 2 + Salutologie 1 und PSOB - Akademie f\u00fcr Salutologie\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/salutologie.org\/#website\"},\"datePublished\":\"2020-11-18T16:13:48+00:00\",\"dateModified\":\"2026-05-08T09:10:07+00:00\",\"description\":\"Der Lehrgang vertieft salutologisches Denken und bef\u00e4higt Sie, mit erweitertem Methodenrepertoire gesundheitsf\u00f6rdernd zu beraten.\",\"breadcrumb\":{\"@id\":\"https:\/\/salutologie.org\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/salutologie.org\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/salutologie.org\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/salutologie.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausbildungen\",\"item\":\"https:\/\/salutologie.org\/ausbildungen\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Zertifikatslehrgang &#8211; LSB Salutologie 2 + Salutologie 1 und PSOB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/salutologie.org\/#website\",\"url\":\"https:\/\/salutologie.org\/\",\"name\":\"Akademie f\u00fcr Salutologie\u00ae\",\"description\":\"Akademie f\u00fcr Salutologie\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/salutologie.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zertifikatslehrgang - LSB Salutologie 2 + Salutologie 1 und PSOB - Akademie f\u00fcr Salutologie\u00ae","description":"Der Lehrgang vertieft salutologisches Denken und bef\u00e4higt Sie, mit erweitertem Methodenrepertoire gesundheitsf\u00f6rdernd zu beraten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salutologie.org\/en\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/","og_locale":"en_GB","og_type":"article","og_title":"Akademie f\u00fcr Salutologie \u2013 Zertifikatslehrgang \u2013 LSB Salutologie 2 + Salutologie 1 + PSOB | Zertifikat f\u00fcr Beratung & Gesundheit","og_description":"Der Lehrgang vertieft salutologisches Denken und bef\u00e4higt Sie, mit erweitertem Methodenrepertoire gesundheitsf\u00f6rdernd zu beraten.","og_url":"https:\/\/salutologie.org\/en\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/","og_site_name":"Akademie f\u00fcr Salutologie\u00ae","article_modified_time":"2026-05-08T09:10:07+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/salutologie.org\/wp-content\/uploads\/2023\/01\/1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/salutologie.org\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/","url":"https:\/\/salutologie.org\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/","name":"Zertifikatslehrgang - LSB Salutologie 2 + Salutologie 1 und PSOB - Akademie f\u00fcr Salutologie\u00ae","isPartOf":{"@id":"https:\/\/salutologie.org\/#website"},"datePublished":"2020-11-18T16:13:48+00:00","dateModified":"2026-05-08T09:10:07+00:00","description":"Der Lehrgang vertieft salutologisches Denken und bef\u00e4higt Sie, mit erweitertem Methodenrepertoire gesundheitsf\u00f6rdernd zu beraten.","breadcrumb":{"@id":"https:\/\/salutologie.org\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salutologie.org\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/salutologie.org\/ausbildungen\/zertifikatslehrgang-lsb-salutologie-2-salutologie-1-und-psob\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/salutologie.org\/"},{"@type":"ListItem","position":2,"name":"Ausbildungen","item":"https:\/\/salutologie.org\/ausbildungen\/"},{"@type":"ListItem","position":3,"name":"Zertifikatslehrgang &#8211; LSB Salutologie 2 + Salutologie 1 und PSOB"}]},{"@type":"WebSite","@id":"https:\/\/salutologie.org\/#website","url":"https:\/\/salutologie.org\/","name":"Akademie f\u00fcr Salutologie\u00ae","description":"Akademie f\u00fcr Salutologie\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salutologie.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/pages\/3753"}],"collection":[{"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/comments?post=3753"}],"version-history":[{"count":32,"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/pages\/3753\/revisions"}],"predecessor-version":[{"id":5817,"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/pages\/3753\/revisions\/5817"}],"up":[{"embeddable":true,"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/pages\/357"}],"wp:attachment":[{"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/media?parent=3753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}