{"id":3098,"date":"2020-06-24T19:46:15","date_gmt":"2020-06-24T17:46:15","guid":{"rendered":"https:\/\/chronoinstitut.org\/?p=3098"},"modified":"2020-07-14T21:04:11","modified_gmt":"2020-07-14T19:04:11","slug":"publikationen-wirtschaft","status":"publish","type":"post","link":"https:\/\/salutologie.org\/en\/publikationen-wirtschaft\/","title":{"rendered":"Wirtschaft"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><div class=\"block-area stripe wpb_row default with-border vc_row-fluid\"><div class=\"container clearfix\">\n\t<div class=\"vc_col-sm-12 wpb_column column_container\" style=\"\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"gap\" style=\"line-height: 50px; height: 50px;\"><\/div>\n\t\t<\/div> \n\t<\/div> \n<\/div><\/div><div class=\"block-area stripe wpb_row default with-border vc_row-fluid\"><div class=\"container clearfix\">\n\t<div class=\"vc_col-sm-6 wpb_column column_container\" style=\"\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t<div class=\"wpb_text_column wpb_content_element\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1>B\u00fccher<\/h1>\n\n\t\t<\/div> \n\t<\/div> \n\t\t<\/div> \n\t<\/div> \n\n\t<div class=\"vc_col-sm-6 wpb_column column_container\" style=\"\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t\n\t\t<\/div> \n\t<\/div> \n<\/div><\/div><div class=\"block-area stripe wpb_row default with-border vc_row-fluid\"><div class=\"container clearfix\">\n\t<div class=\"vc_col-sm-12 wpb_column column_container\" style=\"\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"gap\" style=\"line-height: 30px; height: 30px;\"><\/div>\n\t\t<\/div> \n\t<\/div> \n<\/div><\/div><div class=\"block-area stripe wpb_row default with-border vc_row-fluid\"><div class=\"container clearfix\">\n\t<div class=\"vc_col-sm-12 wpb_column column_container\" style=\"\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"box-list-wrapper blog-list-wrapper type1\"><div class=\"bubblingG\"><span class=\"bubblingG_1\"><\/span><span class=\"bubblingG_2\"><\/span><span class=\"bubblingG_3\"><\/span><\/div><div class=\"box-list clearfix type1 masonry\" data-column-number=\"3\"><div class=\"box-list-item vc_col-sm-4\">\n        \n                                <div id=\"post-1625\" class=\"box-item no-author-image post-1625 post type-post status-publish format-standard has-post-thumbnail hentry category-publikationen-wirtschaft-buecher\">\n\n                    <div class=\"detail-area\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<h3 class=\"main-head-text masonry\"><a href=\"https:\/\/salutologie.org\/en\/praevention-von-erschoepfung-in-der-arbeitswelt\/\">Pr\u00e4vention von Ersch\u00f6pfung in der Arbeitswelt<\/a><\/h3>\n                        \t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"figure-area\">\n\t\t\t\t\t\t\t<figure class=\"featured-image\"><a href=\"https:\/\/salutologie.org\/en\/praevention-von-erschoepfung-in-der-arbeitswelt\/\"><img width=\"600\" height=\"400\" src=\"https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-1-600x400.png\" class=\"attachment-img_size_600x400 size-img_size_600x400 wp-post-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-1-600x400.png 600w, https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-1-300x200.png 300w, https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-1-1024x683.png 1024w, https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-1-768x512.png 768w, https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-1-900x600.png 900w, https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-1-1200x800.png 1200w, https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-1.png 1500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n                            \n                                                            <div class=\"caption\"><p>Von Ingrid Pirker-Binder<\/p>\n<\/div>\n                                \n                                                        \n                                                        <a class=\"read-more\" href=\"https:\/\/salutologie.org\/en\/praevention-von-erschoepfung-in-der-arbeitswelt\/\">Read More<\/a>\n                                                    <\/div>\n\n                <\/div>\n\n        \n        \n        <\/div><div class=\"box-list-item vc_col-sm-4\">\n        \n                                <div id=\"post-1629\" class=\"box-item no-author-image post-1629 post type-post status-publish format-standard has-post-thumbnail hentry category-publikationen-wirtschaft-buecher\">\n\n                    <div class=\"detail-area\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<h3 class=\"main-head-text masonry\"><a href=\"https:\/\/salutologie.org\/en\/mindful-prevention-of-burnout-in-workplace-health-management\/\">Mindful Prevention of Burnout in Workplace Health Management<\/a><\/h3>\n                        \t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"figure-area\">\n\t\t\t\t\t\t\t<figure class=\"featured-image\"><a href=\"https:\/\/salutologie.org\/en\/mindful-prevention-of-burnout-in-workplace-health-management\/\"><img width=\"600\" height=\"400\" src=\"https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-3-600x400.png\" class=\"attachment-img_size_600x400 size-img_size_600x400 wp-post-image\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-3-600x400.png 600w, https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-3-300x200.png 300w, https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-3-1024x683.png 1024w, https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-3-768x512.png 768w, https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-3-900x600.png 900w, https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-3-1200x800.png 1200w, https:\/\/salutologie.org\/wp-content\/uploads\/2020\/04\/Pirker-Binder-3.png 1500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\n                            \n                                                            <div class=\"caption\"><p>Von Ingrid Pirker-Binder<\/p>\n<\/div>\n                                \n                                                        \n                                                        <a class=\"read-more\" href=\"https:\/\/salutologie.org\/en\/mindful-prevention-of-burnout-in-workplace-health-management\/\">Read More<\/a>\n                                                    <\/div>\n\n                <\/div>\n\n        \n        \n        <\/div><\/div><\/div>\n\t\t<\/div> \n\t<\/div> \n<\/div><\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>Alles zum Thema Wirtschaft<\/p>","protected":false},"author":1,"featured_media":3090,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Wirtschaft - Akademie f\u00fcr Salutologie\u00ae<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/salutologie.org\/en\/publikationen-wirtschaft\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wirtschaft - Akademie f\u00fcr Salutologie\u00ae\" \/>\n<meta property=\"og:description\" content=\"Alles zum Thema Wirtschaft\" \/>\n<meta property=\"og:url\" content=\"https:\/\/salutologie.org\/en\/publikationen-wirtschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"Akademie f\u00fcr Salutologie\u00ae\" \/>\n<meta property=\"article:published_time\" content=\"2020-06-24T17:46:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-14T19:04:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/salutologie.org\/wp-content\/uploads\/2020\/06\/photo-of-people-doing-handshakes-3183197-copy-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1998\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"wp-admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"wp-admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/salutologie.org\/publikationen-wirtschaft\/\",\"url\":\"https:\/\/salutologie.org\/publikationen-wirtschaft\/\",\"name\":\"Wirtschaft - Akademie f\u00fcr Salutologie\u00ae\",\"isPartOf\":{\"@id\":\"https:\/\/salutologie.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/salutologie.org\/publikationen-wirtschaft\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/salutologie.org\/publikationen-wirtschaft\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/salutologie.org\/wp-content\/uploads\/2020\/06\/photo-of-people-doing-handshakes-3183197-copy-2.jpg\",\"datePublished\":\"2020-06-24T17:46:15+00:00\",\"dateModified\":\"2020-07-14T19:04:11+00:00\",\"author\":{\"@id\":\"https:\/\/salutologie.org\/#\/schema\/person\/828e3d339c739b762a4294433c05a9ce\"},\"breadcrumb\":{\"@id\":\"https:\/\/salutologie.org\/publikationen-wirtschaft\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/salutologie.org\/publikationen-wirtschaft\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/salutologie.org\/publikationen-wirtschaft\/#primaryimage\",\"url\":\"https:\/\/salutologie.org\/wp-content\/uploads\/2020\/06\/photo-of-people-doing-handshakes-3183197-copy-2.jpg\",\"contentUrl\":\"https:\/\/salutologie.org\/wp-content\/uploads\/2020\/06\/photo-of-people-doing-handshakes-3183197-copy-2.jpg\",\"width\":1998,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/salutologie.org\/publikationen-wirtschaft\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/salutologie.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wirtschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/salutologie.org\/#website\",\"url\":\"https:\/\/salutologie.org\/\",\"name\":\"Akademie f\u00fcr Salutologie\u00ae\",\"description\":\"Akademie f\u00fcr Salutologie\u00ae\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/salutologie.org\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/salutologie.org\/#\/schema\/person\/828e3d339c739b762a4294433c05a9ce\",\"name\":\"wp-admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/salutologie.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d9646857442a8843a3b62a0dda760756?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d9646857442a8843a3b62a0dda760756?s=96&d=mm&r=g\",\"caption\":\"wp-admin\"},\"url\":\"https:\/\/salutologie.org\/en\/author\/wp-admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wirtschaft - Akademie f\u00fcr Salutologie\u00ae","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/salutologie.org\/en\/publikationen-wirtschaft\/","og_locale":"en_GB","og_type":"article","og_title":"Wirtschaft - Akademie f\u00fcr Salutologie\u00ae","og_description":"Alles zum Thema Wirtschaft","og_url":"https:\/\/salutologie.org\/en\/publikationen-wirtschaft\/","og_site_name":"Akademie f\u00fcr Salutologie\u00ae","article_published_time":"2020-06-24T17:46:15+00:00","article_modified_time":"2020-07-14T19:04:11+00:00","og_image":[{"width":1998,"height":666,"url":"https:\/\/salutologie.org\/wp-content\/uploads\/2020\/06\/photo-of-people-doing-handshakes-3183197-copy-2.jpg","type":"image\/jpeg"}],"author":"wp-admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"wp-admin","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/salutologie.org\/publikationen-wirtschaft\/","url":"https:\/\/salutologie.org\/publikationen-wirtschaft\/","name":"Wirtschaft - Akademie f\u00fcr Salutologie\u00ae","isPartOf":{"@id":"https:\/\/salutologie.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/salutologie.org\/publikationen-wirtschaft\/#primaryimage"},"image":{"@id":"https:\/\/salutologie.org\/publikationen-wirtschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/salutologie.org\/wp-content\/uploads\/2020\/06\/photo-of-people-doing-handshakes-3183197-copy-2.jpg","datePublished":"2020-06-24T17:46:15+00:00","dateModified":"2020-07-14T19:04:11+00:00","author":{"@id":"https:\/\/salutologie.org\/#\/schema\/person\/828e3d339c739b762a4294433c05a9ce"},"breadcrumb":{"@id":"https:\/\/salutologie.org\/publikationen-wirtschaft\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/salutologie.org\/publikationen-wirtschaft\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/salutologie.org\/publikationen-wirtschaft\/#primaryimage","url":"https:\/\/salutologie.org\/wp-content\/uploads\/2020\/06\/photo-of-people-doing-handshakes-3183197-copy-2.jpg","contentUrl":"https:\/\/salutologie.org\/wp-content\/uploads\/2020\/06\/photo-of-people-doing-handshakes-3183197-copy-2.jpg","width":1998,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/salutologie.org\/publikationen-wirtschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/salutologie.org\/"},{"@type":"ListItem","position":2,"name":"Wirtschaft"}]},{"@type":"WebSite","@id":"https:\/\/salutologie.org\/#website","url":"https:\/\/salutologie.org\/","name":"Akademie f\u00fcr Salutologie\u00ae","description":"Akademie f\u00fcr Salutologie\u00ae","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/salutologie.org\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/salutologie.org\/#\/schema\/person\/828e3d339c739b762a4294433c05a9ce","name":"wp-admin","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/salutologie.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d9646857442a8843a3b62a0dda760756?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d9646857442a8843a3b62a0dda760756?s=96&d=mm&r=g","caption":"wp-admin"},"url":"https:\/\/salutologie.org\/en\/author\/wp-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/posts\/3098"}],"collection":[{"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/comments?post=3098"}],"version-history":[{"count":7,"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/posts\/3098\/revisions"}],"predecessor-version":[{"id":3306,"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/posts\/3098\/revisions\/3306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/media\/3090"}],"wp:attachment":[{"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/media?parent=3098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/categories?post=3098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/salutologie.org\/en\/wp-json\/wp\/v2\/tags?post=3098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}